{"id":2025,"date":"2019-04-08T12:08:39","date_gmt":"2019-04-08T10:08:39","guid":{"rendered":"http:\/\/www.equipespopulaires.be\/verviers\/?p=2025"},"modified":"2022-10-05T21:39:40","modified_gmt":"2022-10-05T19:39:40","slug":"porteurs-de-paroles","status":"publish","type":"post","link":"https:\/\/www.equipespopulaires.be\/verviers\/2019\/04\/08\/porteurs-de-paroles\/","title":{"rendered":"&laquo;&nbsp;Porteurs de paroles&nbsp;&raquo; ce 3 avril 2019"},"content":{"rendered":"","protected":false},"excerpt":{"rendered":"","protected":false},"author":9,"featured_media":0,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[1],"tags":[],"class_list":["post-2025","post","type-post","status-publish","format-standard","hentry","category-non-classe"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>&quot;Porteurs de paroles&quot; ce 3 avril 2019 - Verviers<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.equipespopulaires.be\/verviers\/2019\/04\/08\/porteurs-de-paroles\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"&quot;Porteurs de paroles&quot; ce 3 avril 2019 - Verviers\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.equipespopulaires.be\/verviers\/2019\/04\/08\/porteurs-de-paroles\/\" \/>\n<meta property=\"og:site_name\" content=\"Verviers\" \/>\n<meta property=\"article:published_time\" content=\"2019-04-08T10:08:39+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2022-10-05T19:39:40+00:00\" \/>\n<meta name=\"author\" content=\"Claudia Benedetto\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"\u00c9crit par\" \/>\n\t<meta name=\"twitter:data1\" content=\"Claudia Benedetto\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.equipespopulaires.be\\\/verviers\\\/2019\\\/04\\\/08\\\/porteurs-de-paroles\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.equipespopulaires.be\\\/verviers\\\/2019\\\/04\\\/08\\\/porteurs-de-paroles\\\/\"},\"author\":{\"name\":\"Claudia Benedetto\",\"@id\":\"https:\\\/\\\/www.equipespopulaires.be\\\/verviers\\\/#\\\/schema\\\/person\\\/6e6e325653b9536dab00945b1f1c08dc\"},\"headline\":\"&laquo;&nbsp;Porteurs de paroles&nbsp;&raquo; ce 3 avril 2019\",\"datePublished\":\"2019-04-08T10:08:39+00:00\",\"dateModified\":\"2022-10-05T19:39:40+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.equipespopulaires.be\\\/verviers\\\/2019\\\/04\\\/08\\\/porteurs-de-paroles\\\/\"},\"wordCount\":5,\"inLanguage\":\"fr-FR\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.equipespopulaires.be\\\/verviers\\\/2019\\\/04\\\/08\\\/porteurs-de-paroles\\\/\",\"url\":\"https:\\\/\\\/www.equipespopulaires.be\\\/verviers\\\/2019\\\/04\\\/08\\\/porteurs-de-paroles\\\/\",\"name\":\"\\\"Porteurs de paroles\\\" ce 3 avril 2019 - Verviers\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.equipespopulaires.be\\\/verviers\\\/#website\"},\"datePublished\":\"2019-04-08T10:08:39+00:00\",\"dateModified\":\"2022-10-05T19:39:40+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/www.equipespopulaires.be\\\/verviers\\\/#\\\/schema\\\/person\\\/6e6e325653b9536dab00945b1f1c08dc\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.equipespopulaires.be\\\/verviers\\\/2019\\\/04\\\/08\\\/porteurs-de-paroles\\\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.equipespopulaires.be\\\/verviers\\\/2019\\\/04\\\/08\\\/porteurs-de-paroles\\\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.equipespopulaires.be\\\/verviers\\\/2019\\\/04\\\/08\\\/porteurs-de-paroles\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Les \u00c9quipes Populaires\",\"item\":\"https:\\\/\\\/www.equipespopulaires.be\\\/verviers\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"&laquo;&nbsp;Porteurs de paroles&nbsp;&raquo; ce 3 avril 2019\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.equipespopulaires.be\\\/verviers\\\/#website\",\"url\":\"https:\\\/\\\/www.equipespopulaires.be\\\/verviers\\\/\",\"name\":\"Verviers\",\"description\":\"Un site utilisant Sites Les \u00e9quipes populaires\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.equipespopulaires.be\\\/verviers\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.equipespopulaires.be\\\/verviers\\\/#\\\/schema\\\/person\\\/6e6e325653b9536dab00945b1f1c08dc\",\"name\":\"Claudia Benedetto\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/44aab6ef74327ab55dc41964fd514ba4eee26d2d7fed6f037191b713bfc8cac8?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/44aab6ef74327ab55dc41964fd514ba4eee26d2d7fed6f037191b713bfc8cac8?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/44aab6ef74327ab55dc41964fd514ba4eee26d2d7fed6f037191b713bfc8cac8?s=96&d=mm&r=g\",\"caption\":\"Claudia Benedetto\"},\"url\":\"https:\\\/\\\/www.equipespopulaires.be\\\/verviers\\\/author\\\/benedetto\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"\"Porteurs de paroles\" ce 3 avril 2019 - Verviers","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.equipespopulaires.be\/verviers\/2019\/04\/08\/porteurs-de-paroles\/","og_locale":"fr_FR","og_type":"article","og_title":"\"Porteurs de paroles\" ce 3 avril 2019 - Verviers","og_url":"https:\/\/www.equipespopulaires.be\/verviers\/2019\/04\/08\/porteurs-de-paroles\/","og_site_name":"Verviers","article_published_time":"2019-04-08T10:08:39+00:00","article_modified_time":"2022-10-05T19:39:40+00:00","author":"Claudia Benedetto","twitter_card":"summary_large_image","twitter_misc":{"\u00c9crit par":"Claudia Benedetto"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.equipespopulaires.be\/verviers\/2019\/04\/08\/porteurs-de-paroles\/#article","isPartOf":{"@id":"https:\/\/www.equipespopulaires.be\/verviers\/2019\/04\/08\/porteurs-de-paroles\/"},"author":{"name":"Claudia Benedetto","@id":"https:\/\/www.equipespopulaires.be\/verviers\/#\/schema\/person\/6e6e325653b9536dab00945b1f1c08dc"},"headline":"&laquo;&nbsp;Porteurs de paroles&nbsp;&raquo; ce 3 avril 2019","datePublished":"2019-04-08T10:08:39+00:00","dateModified":"2022-10-05T19:39:40+00:00","mainEntityOfPage":{"@id":"https:\/\/www.equipespopulaires.be\/verviers\/2019\/04\/08\/porteurs-de-paroles\/"},"wordCount":5,"inLanguage":"fr-FR"},{"@type":"WebPage","@id":"https:\/\/www.equipespopulaires.be\/verviers\/2019\/04\/08\/porteurs-de-paroles\/","url":"https:\/\/www.equipespopulaires.be\/verviers\/2019\/04\/08\/porteurs-de-paroles\/","name":"\"Porteurs de paroles\" ce 3 avril 2019 - Verviers","isPartOf":{"@id":"https:\/\/www.equipespopulaires.be\/verviers\/#website"},"datePublished":"2019-04-08T10:08:39+00:00","dateModified":"2022-10-05T19:39:40+00:00","author":{"@id":"https:\/\/www.equipespopulaires.be\/verviers\/#\/schema\/person\/6e6e325653b9536dab00945b1f1c08dc"},"breadcrumb":{"@id":"https:\/\/www.equipespopulaires.be\/verviers\/2019\/04\/08\/porteurs-de-paroles\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.equipespopulaires.be\/verviers\/2019\/04\/08\/porteurs-de-paroles\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/www.equipespopulaires.be\/verviers\/2019\/04\/08\/porteurs-de-paroles\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Les \u00c9quipes Populaires","item":"https:\/\/www.equipespopulaires.be\/verviers\/"},{"@type":"ListItem","position":2,"name":"&laquo;&nbsp;Porteurs de paroles&nbsp;&raquo; ce 3 avril 2019"}]},{"@type":"WebSite","@id":"https:\/\/www.equipespopulaires.be\/verviers\/#website","url":"https:\/\/www.equipespopulaires.be\/verviers\/","name":"Verviers","description":"Un site utilisant Sites Les \u00e9quipes populaires","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.equipespopulaires.be\/verviers\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"Person","@id":"https:\/\/www.equipespopulaires.be\/verviers\/#\/schema\/person\/6e6e325653b9536dab00945b1f1c08dc","name":"Claudia Benedetto","image":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/secure.gravatar.com\/avatar\/44aab6ef74327ab55dc41964fd514ba4eee26d2d7fed6f037191b713bfc8cac8?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/44aab6ef74327ab55dc41964fd514ba4eee26d2d7fed6f037191b713bfc8cac8?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/44aab6ef74327ab55dc41964fd514ba4eee26d2d7fed6f037191b713bfc8cac8?s=96&d=mm&r=g","caption":"Claudia Benedetto"},"url":"https:\/\/www.equipespopulaires.be\/verviers\/author\/benedetto\/"}]}},"_links":{"self":[{"href":"https:\/\/www.equipespopulaires.be\/verviers\/wp-json\/wp\/v2\/posts\/2025","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.equipespopulaires.be\/verviers\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.equipespopulaires.be\/verviers\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.equipespopulaires.be\/verviers\/wp-json\/wp\/v2\/users\/9"}],"replies":[{"embeddable":true,"href":"https:\/\/www.equipespopulaires.be\/verviers\/wp-json\/wp\/v2\/comments?post=2025"}],"version-history":[{"count":14,"href":"https:\/\/www.equipespopulaires.be\/verviers\/wp-json\/wp\/v2\/posts\/2025\/revisions"}],"predecessor-version":[{"id":2060,"href":"https:\/\/www.equipespopulaires.be\/verviers\/wp-json\/wp\/v2\/posts\/2025\/revisions\/2060"}],"wp:attachment":[{"href":"https:\/\/www.equipespopulaires.be\/verviers\/wp-json\/wp\/v2\/media?parent=2025"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.equipespopulaires.be\/verviers\/wp-json\/wp\/v2\/categories?post=2025"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.equipespopulaires.be\/verviers\/wp-json\/wp\/v2\/tags?post=2025"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}