{"id":2554,"date":"2023-01-26T11:34:39","date_gmt":"2023-01-26T10:34:39","guid":{"rendered":"https:\/\/www.equipespopulaires.be\/verviers\/?p=2554"},"modified":"2023-01-26T11:34:39","modified_gmt":"2023-01-26T10:34:39","slug":"25-novembre-journee-internationale-de-lutte-contre-les-violences-faites-aux-femmes","status":"publish","type":"post","link":"https:\/\/www.equipespopulaires.be\/verviers\/2023\/01\/26\/25-novembre-journee-internationale-de-lutte-contre-les-violences-faites-aux-femmes\/","title":{"rendered":"25 novembre &ndash; Jour&shy;n&eacute;e inter&shy;na&shy;tio&shy;nale de lutte contre les violences faites aux femmes"},"content":{"rendered":"","protected":false},"excerpt":{"rendered":"","protected":false},"author":63,"featured_media":0,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[1],"tags":[],"class_list":["post-2554","post","type-post","status-publish","format-standard","hentry","category-non-classe"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>25 novembre - Journ\u00e9e internationale de lutte contre les violences faites aux femmes - Verviers<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.equipespopulaires.be\/verviers\/2023\/01\/26\/25-novembre-journee-internationale-de-lutte-contre-les-violences-faites-aux-femmes\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"25 novembre - Journ\u00e9e internationale de lutte contre les violences faites aux femmes - Verviers\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.equipespopulaires.be\/verviers\/2023\/01\/26\/25-novembre-journee-internationale-de-lutte-contre-les-violences-faites-aux-femmes\/\" \/>\n<meta property=\"og:site_name\" content=\"Verviers\" \/>\n<meta property=\"article:published_time\" content=\"2023-01-26T10:34:39+00:00\" \/>\n<meta name=\"author\" content=\"ep2022site\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"\u00c9crit par\" \/>\n\t<meta name=\"twitter:data1\" content=\"ep2022site\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.equipespopulaires.be\\\/verviers\\\/2023\\\/01\\\/26\\\/25-novembre-journee-internationale-de-lutte-contre-les-violences-faites-aux-femmes\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.equipespopulaires.be\\\/verviers\\\/2023\\\/01\\\/26\\\/25-novembre-journee-internationale-de-lutte-contre-les-violences-faites-aux-femmes\\\/\"},\"author\":{\"name\":\"ep2022site\",\"@id\":\"https:\\\/\\\/www.equipespopulaires.be\\\/verviers\\\/#\\\/schema\\\/person\\\/b124622d00f244685e1a5d9ef84cf0ff\"},\"headline\":\"25 novembre &ndash; Jour&shy;n&eacute;e inter&shy;na&shy;tio&shy;nale de lutte contre les violences faites aux femmes\",\"datePublished\":\"2023-01-26T10:34:39+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.equipespopulaires.be\\\/verviers\\\/2023\\\/01\\\/26\\\/25-novembre-journee-internationale-de-lutte-contre-les-violences-faites-aux-femmes\\\/\"},\"wordCount\":13,\"inLanguage\":\"fr-FR\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.equipespopulaires.be\\\/verviers\\\/2023\\\/01\\\/26\\\/25-novembre-journee-internationale-de-lutte-contre-les-violences-faites-aux-femmes\\\/\",\"url\":\"https:\\\/\\\/www.equipespopulaires.be\\\/verviers\\\/2023\\\/01\\\/26\\\/25-novembre-journee-internationale-de-lutte-contre-les-violences-faites-aux-femmes\\\/\",\"name\":\"25 novembre - Journ\u00e9e internationale de lutte contre les violences faites aux femmes - Verviers\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.equipespopulaires.be\\\/verviers\\\/#website\"},\"datePublished\":\"2023-01-26T10:34:39+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/www.equipespopulaires.be\\\/verviers\\\/#\\\/schema\\\/person\\\/b124622d00f244685e1a5d9ef84cf0ff\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.equipespopulaires.be\\\/verviers\\\/2023\\\/01\\\/26\\\/25-novembre-journee-internationale-de-lutte-contre-les-violences-faites-aux-femmes\\\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.equipespopulaires.be\\\/verviers\\\/2023\\\/01\\\/26\\\/25-novembre-journee-internationale-de-lutte-contre-les-violences-faites-aux-femmes\\\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.equipespopulaires.be\\\/verviers\\\/2023\\\/01\\\/26\\\/25-novembre-journee-internationale-de-lutte-contre-les-violences-faites-aux-femmes\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Les \u00c9quipes Populaires\",\"item\":\"https:\\\/\\\/www.equipespopulaires.be\\\/verviers\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"25 novembre &ndash; Jour&shy;&shy;n&eacute;e inter&shy;&shy;&shy;na&shy;&shy;tio&shy;&shy;nale de lutte contre les violences faites aux femmes\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.equipespopulaires.be\\\/verviers\\\/#website\",\"url\":\"https:\\\/\\\/www.equipespopulaires.be\\\/verviers\\\/\",\"name\":\"Verviers\",\"description\":\"Un site utilisant Sites Les \u00e9quipes populaires\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.equipespopulaires.be\\\/verviers\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.equipespopulaires.be\\\/verviers\\\/#\\\/schema\\\/person\\\/b124622d00f244685e1a5d9ef84cf0ff\",\"name\":\"ep2022site\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/eea0222f618fbb482586275fa8063d7393f73237bf681b3ef65208d02f8d14a9?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/eea0222f618fbb482586275fa8063d7393f73237bf681b3ef65208d02f8d14a9?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/eea0222f618fbb482586275fa8063d7393f73237bf681b3ef65208d02f8d14a9?s=96&d=mm&r=g\",\"caption\":\"ep2022site\"},\"url\":\"https:\\\/\\\/www.equipespopulaires.be\\\/verviers\\\/author\\\/ep2022site\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"25 novembre - Journ\u00e9e internationale de lutte contre les violences faites aux femmes - Verviers","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.equipespopulaires.be\/verviers\/2023\/01\/26\/25-novembre-journee-internationale-de-lutte-contre-les-violences-faites-aux-femmes\/","og_locale":"fr_FR","og_type":"article","og_title":"25 novembre - Journ\u00e9e internationale de lutte contre les violences faites aux femmes - Verviers","og_url":"https:\/\/www.equipespopulaires.be\/verviers\/2023\/01\/26\/25-novembre-journee-internationale-de-lutte-contre-les-violences-faites-aux-femmes\/","og_site_name":"Verviers","article_published_time":"2023-01-26T10:34:39+00:00","author":"ep2022site","twitter_card":"summary_large_image","twitter_misc":{"\u00c9crit par":"ep2022site"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.equipespopulaires.be\/verviers\/2023\/01\/26\/25-novembre-journee-internationale-de-lutte-contre-les-violences-faites-aux-femmes\/#article","isPartOf":{"@id":"https:\/\/www.equipespopulaires.be\/verviers\/2023\/01\/26\/25-novembre-journee-internationale-de-lutte-contre-les-violences-faites-aux-femmes\/"},"author":{"name":"ep2022site","@id":"https:\/\/www.equipespopulaires.be\/verviers\/#\/schema\/person\/b124622d00f244685e1a5d9ef84cf0ff"},"headline":"25 novembre &ndash; Jour&shy;n&eacute;e inter&shy;na&shy;tio&shy;nale de lutte contre les violences faites aux femmes","datePublished":"2023-01-26T10:34:39+00:00","mainEntityOfPage":{"@id":"https:\/\/www.equipespopulaires.be\/verviers\/2023\/01\/26\/25-novembre-journee-internationale-de-lutte-contre-les-violences-faites-aux-femmes\/"},"wordCount":13,"inLanguage":"fr-FR"},{"@type":"WebPage","@id":"https:\/\/www.equipespopulaires.be\/verviers\/2023\/01\/26\/25-novembre-journee-internationale-de-lutte-contre-les-violences-faites-aux-femmes\/","url":"https:\/\/www.equipespopulaires.be\/verviers\/2023\/01\/26\/25-novembre-journee-internationale-de-lutte-contre-les-violences-faites-aux-femmes\/","name":"25 novembre - Journ\u00e9e internationale de lutte contre les violences faites aux femmes - Verviers","isPartOf":{"@id":"https:\/\/www.equipespopulaires.be\/verviers\/#website"},"datePublished":"2023-01-26T10:34:39+00:00","author":{"@id":"https:\/\/www.equipespopulaires.be\/verviers\/#\/schema\/person\/b124622d00f244685e1a5d9ef84cf0ff"},"breadcrumb":{"@id":"https:\/\/www.equipespopulaires.be\/verviers\/2023\/01\/26\/25-novembre-journee-internationale-de-lutte-contre-les-violences-faites-aux-femmes\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.equipespopulaires.be\/verviers\/2023\/01\/26\/25-novembre-journee-internationale-de-lutte-contre-les-violences-faites-aux-femmes\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/www.equipespopulaires.be\/verviers\/2023\/01\/26\/25-novembre-journee-internationale-de-lutte-contre-les-violences-faites-aux-femmes\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Les \u00c9quipes Populaires","item":"https:\/\/www.equipespopulaires.be\/verviers\/"},{"@type":"ListItem","position":2,"name":"25 novembre &ndash; Jour&shy;&shy;n&eacute;e inter&shy;&shy;&shy;na&shy;&shy;tio&shy;&shy;nale de lutte contre les violences faites aux femmes"}]},{"@type":"WebSite","@id":"https:\/\/www.equipespopulaires.be\/verviers\/#website","url":"https:\/\/www.equipespopulaires.be\/verviers\/","name":"Verviers","description":"Un site utilisant Sites Les \u00e9quipes populaires","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.equipespopulaires.be\/verviers\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"Person","@id":"https:\/\/www.equipespopulaires.be\/verviers\/#\/schema\/person\/b124622d00f244685e1a5d9ef84cf0ff","name":"ep2022site","image":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/secure.gravatar.com\/avatar\/eea0222f618fbb482586275fa8063d7393f73237bf681b3ef65208d02f8d14a9?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/eea0222f618fbb482586275fa8063d7393f73237bf681b3ef65208d02f8d14a9?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/eea0222f618fbb482586275fa8063d7393f73237bf681b3ef65208d02f8d14a9?s=96&d=mm&r=g","caption":"ep2022site"},"url":"https:\/\/www.equipespopulaires.be\/verviers\/author\/ep2022site\/"}]}},"_links":{"self":[{"href":"https:\/\/www.equipespopulaires.be\/verviers\/wp-json\/wp\/v2\/posts\/2554","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.equipespopulaires.be\/verviers\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.equipespopulaires.be\/verviers\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.equipespopulaires.be\/verviers\/wp-json\/wp\/v2\/users\/63"}],"replies":[{"embeddable":true,"href":"https:\/\/www.equipespopulaires.be\/verviers\/wp-json\/wp\/v2\/comments?post=2554"}],"version-history":[{"count":2,"href":"https:\/\/www.equipespopulaires.be\/verviers\/wp-json\/wp\/v2\/posts\/2554\/revisions"}],"predecessor-version":[{"id":2559,"href":"https:\/\/www.equipespopulaires.be\/verviers\/wp-json\/wp\/v2\/posts\/2554\/revisions\/2559"}],"wp:attachment":[{"href":"https:\/\/www.equipespopulaires.be\/verviers\/wp-json\/wp\/v2\/media?parent=2554"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.equipespopulaires.be\/verviers\/wp-json\/wp\/v2\/categories?post=2554"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.equipespopulaires.be\/verviers\/wp-json\/wp\/v2\/tags?post=2554"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}