{"id":3852,"date":"2025-11-19T11:39:20","date_gmt":"2025-11-19T10:39:20","guid":{"rendered":"https:\/\/www.equipespopulaires.be\/verviers\/?p=3852"},"modified":"2025-11-19T11:39:20","modified_gmt":"2025-11-19T10:39:20","slug":"soutien-a-la-secu-solidaire-de-la-voix-des-sans-papiers-de-verviers","status":"publish","type":"post","link":"https:\/\/www.equipespopulaires.be\/verviers\/2025\/11\/19\/soutien-a-la-secu-solidaire-de-la-voix-des-sans-papiers-de-verviers\/","title":{"rendered":"Soutien &agrave; la s&eacute;cu soli&shy;daire de la Voix des Sans Papiers de Verviers"},"content":{"rendered":"","protected":false},"excerpt":{"rendered":"","protected":false},"author":63,"featured_media":0,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[1],"tags":[],"class_list":["post-3852","post","type-post","status-publish","format-standard","hentry","category-non-classe"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Soutien \u00e0 la s\u00e9cu solidaire de la Voix des Sans Papiers de Verviers - Verviers<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.equipespopulaires.be\/verviers\/2025\/11\/19\/soutien-a-la-secu-solidaire-de-la-voix-des-sans-papiers-de-verviers\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Soutien \u00e0 la s\u00e9cu solidaire de la Voix des Sans Papiers de Verviers - Verviers\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.equipespopulaires.be\/verviers\/2025\/11\/19\/soutien-a-la-secu-solidaire-de-la-voix-des-sans-papiers-de-verviers\/\" \/>\n<meta property=\"og:site_name\" content=\"Verviers\" \/>\n<meta property=\"article:published_time\" content=\"2025-11-19T10:39:20+00:00\" \/>\n<meta name=\"author\" content=\"ep2022site\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"\u00c9crit par\" \/>\n\t<meta name=\"twitter:data1\" content=\"ep2022site\" \/>\n\t<meta name=\"twitter:label2\" content=\"Dur\u00e9e de lecture estim\u00e9e\" \/>\n\t<meta name=\"twitter:data2\" content=\"3 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.equipespopulaires.be\\\/verviers\\\/2025\\\/11\\\/19\\\/soutien-a-la-secu-solidaire-de-la-voix-des-sans-papiers-de-verviers\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.equipespopulaires.be\\\/verviers\\\/2025\\\/11\\\/19\\\/soutien-a-la-secu-solidaire-de-la-voix-des-sans-papiers-de-verviers\\\/\"},\"author\":{\"name\":\"ep2022site\",\"@id\":\"https:\\\/\\\/www.equipespopulaires.be\\\/verviers\\\/#\\\/schema\\\/person\\\/b124622d00f244685e1a5d9ef84cf0ff\"},\"headline\":\"Soutien &agrave; la s&eacute;cu soli&shy;daire de la Voix des Sans Papiers de Verviers\",\"datePublished\":\"2025-11-19T10:39:20+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.equipespopulaires.be\\\/verviers\\\/2025\\\/11\\\/19\\\/soutien-a-la-secu-solidaire-de-la-voix-des-sans-papiers-de-verviers\\\/\"},\"wordCount\":13,\"inLanguage\":\"fr-FR\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.equipespopulaires.be\\\/verviers\\\/2025\\\/11\\\/19\\\/soutien-a-la-secu-solidaire-de-la-voix-des-sans-papiers-de-verviers\\\/\",\"url\":\"https:\\\/\\\/www.equipespopulaires.be\\\/verviers\\\/2025\\\/11\\\/19\\\/soutien-a-la-secu-solidaire-de-la-voix-des-sans-papiers-de-verviers\\\/\",\"name\":\"Soutien \u00e0 la s\u00e9cu solidaire de la Voix des Sans Papiers de Verviers - Verviers\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.equipespopulaires.be\\\/verviers\\\/#website\"},\"datePublished\":\"2025-11-19T10:39:20+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/www.equipespopulaires.be\\\/verviers\\\/#\\\/schema\\\/person\\\/b124622d00f244685e1a5d9ef84cf0ff\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.equipespopulaires.be\\\/verviers\\\/2025\\\/11\\\/19\\\/soutien-a-la-secu-solidaire-de-la-voix-des-sans-papiers-de-verviers\\\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.equipespopulaires.be\\\/verviers\\\/2025\\\/11\\\/19\\\/soutien-a-la-secu-solidaire-de-la-voix-des-sans-papiers-de-verviers\\\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.equipespopulaires.be\\\/verviers\\\/2025\\\/11\\\/19\\\/soutien-a-la-secu-solidaire-de-la-voix-des-sans-papiers-de-verviers\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Les \u00c9quipes Populaires\",\"item\":\"https:\\\/\\\/www.equipespopulaires.be\\\/verviers\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Soutien &agrave; la s&eacute;cu soli&shy;&shy;daire de la Voix des Sans Papiers de Verviers\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.equipespopulaires.be\\\/verviers\\\/#website\",\"url\":\"https:\\\/\\\/www.equipespopulaires.be\\\/verviers\\\/\",\"name\":\"Verviers\",\"description\":\"Un site utilisant Sites Les \u00e9quipes populaires\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.equipespopulaires.be\\\/verviers\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.equipespopulaires.be\\\/verviers\\\/#\\\/schema\\\/person\\\/b124622d00f244685e1a5d9ef84cf0ff\",\"name\":\"ep2022site\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/eea0222f618fbb482586275fa8063d7393f73237bf681b3ef65208d02f8d14a9?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/eea0222f618fbb482586275fa8063d7393f73237bf681b3ef65208d02f8d14a9?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/eea0222f618fbb482586275fa8063d7393f73237bf681b3ef65208d02f8d14a9?s=96&d=mm&r=g\",\"caption\":\"ep2022site\"},\"url\":\"https:\\\/\\\/www.equipespopulaires.be\\\/verviers\\\/author\\\/ep2022site\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Soutien \u00e0 la s\u00e9cu solidaire de la Voix des Sans Papiers de Verviers - Verviers","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.equipespopulaires.be\/verviers\/2025\/11\/19\/soutien-a-la-secu-solidaire-de-la-voix-des-sans-papiers-de-verviers\/","og_locale":"fr_FR","og_type":"article","og_title":"Soutien \u00e0 la s\u00e9cu solidaire de la Voix des Sans Papiers de Verviers - Verviers","og_url":"https:\/\/www.equipespopulaires.be\/verviers\/2025\/11\/19\/soutien-a-la-secu-solidaire-de-la-voix-des-sans-papiers-de-verviers\/","og_site_name":"Verviers","article_published_time":"2025-11-19T10:39:20+00:00","author":"ep2022site","twitter_card":"summary_large_image","twitter_misc":{"\u00c9crit par":"ep2022site","Dur\u00e9e de lecture estim\u00e9e":"3 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.equipespopulaires.be\/verviers\/2025\/11\/19\/soutien-a-la-secu-solidaire-de-la-voix-des-sans-papiers-de-verviers\/#article","isPartOf":{"@id":"https:\/\/www.equipespopulaires.be\/verviers\/2025\/11\/19\/soutien-a-la-secu-solidaire-de-la-voix-des-sans-papiers-de-verviers\/"},"author":{"name":"ep2022site","@id":"https:\/\/www.equipespopulaires.be\/verviers\/#\/schema\/person\/b124622d00f244685e1a5d9ef84cf0ff"},"headline":"Soutien &agrave; la s&eacute;cu soli&shy;daire de la Voix des Sans Papiers de Verviers","datePublished":"2025-11-19T10:39:20+00:00","mainEntityOfPage":{"@id":"https:\/\/www.equipespopulaires.be\/verviers\/2025\/11\/19\/soutien-a-la-secu-solidaire-de-la-voix-des-sans-papiers-de-verviers\/"},"wordCount":13,"inLanguage":"fr-FR"},{"@type":"WebPage","@id":"https:\/\/www.equipespopulaires.be\/verviers\/2025\/11\/19\/soutien-a-la-secu-solidaire-de-la-voix-des-sans-papiers-de-verviers\/","url":"https:\/\/www.equipespopulaires.be\/verviers\/2025\/11\/19\/soutien-a-la-secu-solidaire-de-la-voix-des-sans-papiers-de-verviers\/","name":"Soutien \u00e0 la s\u00e9cu solidaire de la Voix des Sans Papiers de Verviers - Verviers","isPartOf":{"@id":"https:\/\/www.equipespopulaires.be\/verviers\/#website"},"datePublished":"2025-11-19T10:39:20+00:00","author":{"@id":"https:\/\/www.equipespopulaires.be\/verviers\/#\/schema\/person\/b124622d00f244685e1a5d9ef84cf0ff"},"breadcrumb":{"@id":"https:\/\/www.equipespopulaires.be\/verviers\/2025\/11\/19\/soutien-a-la-secu-solidaire-de-la-voix-des-sans-papiers-de-verviers\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.equipespopulaires.be\/verviers\/2025\/11\/19\/soutien-a-la-secu-solidaire-de-la-voix-des-sans-papiers-de-verviers\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/www.equipespopulaires.be\/verviers\/2025\/11\/19\/soutien-a-la-secu-solidaire-de-la-voix-des-sans-papiers-de-verviers\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Les \u00c9quipes Populaires","item":"https:\/\/www.equipespopulaires.be\/verviers\/"},{"@type":"ListItem","position":2,"name":"Soutien &agrave; la s&eacute;cu soli&shy;&shy;daire de la Voix des Sans Papiers de Verviers"}]},{"@type":"WebSite","@id":"https:\/\/www.equipespopulaires.be\/verviers\/#website","url":"https:\/\/www.equipespopulaires.be\/verviers\/","name":"Verviers","description":"Un site utilisant Sites Les \u00e9quipes populaires","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.equipespopulaires.be\/verviers\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"Person","@id":"https:\/\/www.equipespopulaires.be\/verviers\/#\/schema\/person\/b124622d00f244685e1a5d9ef84cf0ff","name":"ep2022site","image":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/secure.gravatar.com\/avatar\/eea0222f618fbb482586275fa8063d7393f73237bf681b3ef65208d02f8d14a9?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/eea0222f618fbb482586275fa8063d7393f73237bf681b3ef65208d02f8d14a9?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/eea0222f618fbb482586275fa8063d7393f73237bf681b3ef65208d02f8d14a9?s=96&d=mm&r=g","caption":"ep2022site"},"url":"https:\/\/www.equipespopulaires.be\/verviers\/author\/ep2022site\/"}]}},"_links":{"self":[{"href":"https:\/\/www.equipespopulaires.be\/verviers\/wp-json\/wp\/v2\/posts\/3852","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.equipespopulaires.be\/verviers\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.equipespopulaires.be\/verviers\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.equipespopulaires.be\/verviers\/wp-json\/wp\/v2\/users\/63"}],"replies":[{"embeddable":true,"href":"https:\/\/www.equipespopulaires.be\/verviers\/wp-json\/wp\/v2\/comments?post=3852"}],"version-history":[{"count":8,"href":"https:\/\/www.equipespopulaires.be\/verviers\/wp-json\/wp\/v2\/posts\/3852\/revisions"}],"predecessor-version":[{"id":3865,"href":"https:\/\/www.equipespopulaires.be\/verviers\/wp-json\/wp\/v2\/posts\/3852\/revisions\/3865"}],"wp:attachment":[{"href":"https:\/\/www.equipespopulaires.be\/verviers\/wp-json\/wp\/v2\/media?parent=3852"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.equipespopulaires.be\/verviers\/wp-json\/wp\/v2\/categories?post=3852"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.equipespopulaires.be\/verviers\/wp-json\/wp\/v2\/tags?post=3852"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}